{"id":17570,"date":"2022-07-06T11:25:38","date_gmt":"2022-07-06T09:25:38","guid":{"rendered":"https:\/\/adequat.eu\/de\/?p=17570"},"modified":"2026-01-23T14:35:16","modified_gmt":"2026-01-23T13:35:16","slug":"beschattung-dachterrasse","status":"publish","type":"post","link":"https:\/\/adequat.eu\/de\/aktuell\/anwendungen\/beschattung-dachterrasse\/","title":{"rendered":"Beschattung: Dachterrasse"},"content":{"rendered":"<h2><strong>Beschattung: Dachterrasse <\/strong><\/h2>\n<p><strong>Eine alte Dachterrasse wird zur nat\u00fcrlichen Wohlf\u00fchloase!<\/strong><\/p>\n<p>Suchen Sie nach einer Beschattung f\u00fcr Ihre Dachterrasse? Lassen Sie sich von diesem Projekt inspirieren!<\/p>\n<figure id=\"attachment_17465\" aria-describedby=\"caption-attachment-17465\" style=\"width: 571px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\" wp-image-17465\" src=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-Holz-13-16-cm-verschiedene-Massen-992x1240.jpeg\" alt=\"Dachterrasse gestalten mit Holz\" width=\"571\" height=\"714\" srcset=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-Holz-13-16-cm-verschiedene-Massen-992x1240.jpeg 992w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-Holz-13-16-cm-verschiedene-Massen-800x1000.jpeg 800w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-Holz-13-16-cm-verschiedene-Massen-1200x1500.jpeg 1200w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-Holz-13-16-cm-verschiedene-Massen-384x480.jpeg 384w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-Holz-13-16-cm-verschiedene-Massen-576x720.jpeg 576w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-Holz-13-16-cm-verschiedene-Massen-768x960.jpeg 768w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-Holz-13-16-cm-verschiedene-Massen.jpeg 1440w\" sizes=\"(max-width: 571px) 100vw, 571px\" \/><figcaption id=\"caption-attachment-17465\" class=\"wp-caption-text\"><em><a href=\"https:\/\/adequat.eu\/de\/produkt\/holzpfaehle-holzpfosten\/kastanienpfaehle-kastanienpfosten\/kastanienpfosten-kastanie-pfosten\/\">Holzpfosten Kastanie \u00d8 13-16 cm<\/a><\/em><\/figcaption><\/figure>\n<p>Als wir die Fotos sahen, die Sylvia und Nils beim <strong><a href=\"https:\/\/adequat.eu\/de\/aktuell\/fotowettbewerb-juni-2022\/\">Ad\u00e9quat Foto-Wettbewerb<\/a><\/strong> eingereicht hatten, waren wir direkt begeistert!<\/p>\n<p><strong>Das waren Bilder von einem sehr au\u00dfergew\u00f6hnlichen, sehr kreativen Projekt. <\/strong><\/p>\n<p>Die beiden hatte eine tolle Konstruktion mit unseren <strong><a href=\"https:\/\/adequat.eu\/de\/produkte\/holzpfaehle-holzpfosten\/kastanienpfaehle-kastanienpfosten\/\">Kastanienpfosten<\/a> <\/strong>geschaffen. Das hat uns neugierig gemacht: Wir sahen, dass die Konstruktion der Beschattung diente. Nur was genau sollte beschattet werden? Da wir uns nicht ganz sicher waren, haben wir nachgefragt und diese Antwort erhalten:<\/p>\n<div>\n<blockquote><p><em>Hallo Sarah und liebe Gr\u00fc\u00dfe nach Alphen<br \/>\nFreut uns sehr das wir mit unserer Konstruktion aus den Adequat H\u00f6lzern euer Interesse geweckt haben.Ja, es ist eine Beschattung f\u00fcr die Dachterrasse einer Loftwohnung \u00fcber einer ehemaligen Autowerkstatt. <\/em><\/p>\n<p><em>Wir haben diese Wohnung mit unserer eigenen Kreativit\u00e4t auf den Kopf gestellt und aus sehr vernachl\u00e4ssigten Strukturen eine einzigartige Wohninsel inmitten eines tristen Industriegebietes geschaffen.<\/em><\/p>\n<p><em>F\u00fcr die Renovierung der alten Terrasse fehlte uns jedoch die z\u00fcndende Idee bis wir \u00fcber die Angebotspalette von Adequat gestolpert sind.<\/em><\/p>\n<p><em>Den Ausschnitt im Dach f\u00fcr die Dachterrasse haben wir reaktiviert. Es treffen sich jetzt wieder zwei Ortsparren, zwei Kehlsparren und ein Gradsparren in Form der Rundh\u00f6lzer aus Edelkastanie auf einem St\u00fctzpfosten auf der Au\u00dfenecke des Geb\u00e4udegrundrisses und komplettieren den nautischen Stern in der Dachkonstruktion. <\/em><\/p>\n<p><em>Der Querbalken erm\u00f6glicht das aufh\u00e4ngen von einer Schaukel oder Feuerschale.<\/em><\/p>\n<p><em>Die Pergola soll im laufe der Zeit mit einem Bl\u00e4tterdach begr\u00fcnt werden. Bis dahin \u00fcberbr\u00fccken wir die Zeit mit Bambusmatten in einem Holzrahmen den wir jeweils zwischen die Balken geh\u00e4ngt haben.<\/em><\/p>\n<p>Das Projekt haben wir selber realisiert und sind m\u00e4chtig stolz unsere Bilder auf eurer Homepage wiederzufinden.<\/p>\n<p>Sylvia und Nils (von der Band <a href=\"http:\/\/slinsstrassenkoeter.de\/\" target=\"_blank\" rel=\"noopener\">Slin&#8217;s Strassenk\u00f6ter<\/a>)<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h3>Konstruktion aus Kastanienholz<\/h3>\n<p>Im Team von Ad\u00e9quat waren wir uns schnell einig: Die kreative Konstruktion aus unseren <strong><a href=\"https:\/\/adequat.eu\/de\/produkte\/holzpfaehle-holzpfosten\/\">Rundholzpf\u00e4hlen<\/a> <\/strong>aus Kastanie hat es verdient, zum Gewinner des Monats Juni gew\u00e4hlt zu werden!<\/p>\n<p>Hier das Gewinner-Foto:<\/p>\n<figure id=\"attachment_17466\" aria-describedby=\"caption-attachment-17466\" style=\"width: 992px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-medium wp-image-17466\" src=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Pfosten-13-16-cm-Kaastanienholz-992x992.jpeg\" alt=\"Dach aus Kastanienpfosten\" width=\"992\" height=\"992\" srcset=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Pfosten-13-16-cm-Kaastanienholz-992x992.jpeg 992w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Pfosten-13-16-cm-Kaastanienholz-1200x1200.jpeg 1200w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Pfosten-13-16-cm-Kaastanienholz-150x150.jpeg 150w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Pfosten-13-16-cm-Kaastanienholz-384x384.jpeg 384w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Pfosten-13-16-cm-Kaastanienholz-576x576.jpeg 576w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Pfosten-13-16-cm-Kaastanienholz-768x768.jpeg 768w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Pfosten-13-16-cm-Kaastanienholz-1920x1920.jpeg 1920w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Pfosten-13-16-cm-Kaastanienholz-2560x2560.jpeg 2560w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Pfosten-13-16-cm-Kaastanienholz-100x100.jpeg 100w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/><figcaption id=\"caption-attachment-17466\" class=\"wp-caption-text\"><em>Konstruktion mit Pfosten aus Edelkastanie ( \u00d8 13-16 cm)<\/em><\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_17466-2\" aria-describedby=\"caption-attachment-17466-2\" style=\"width: 202px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/adequat.eu\/de\/produkt\/holzpfaehle-holzpfosten\/kastanienpfaehle-kastanienpfosten\/kastanienpfosten-kastanie-pfosten\/\"><img decoding=\"async\" class=\" wp-image-17466\" src=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2020\/10\/Kastanje_160cm_13-16-2.jpg\" alt=\"Kastanienpfosten\" width=\"202\" height=\"302\" \/><\/a><figcaption id=\"caption-attachment-17466-2\" class=\"wp-caption-text\"><a href=\"https:\/\/adequat.eu\/de\/produkt\/holzpfaehle-holzpfosten\/kastanienpfaehle-kastanienpfosten\/kastanienpfosten-kastanie-pfosten\/\"><em>Kastanienpfosten \u00d8 13-16 cm<\/em><\/a><\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h3>Dachterrasse Vorher<\/h3>\n<p>Einen so krassen Vorher-Nachher-Vergleich hatten wir schon lange nicht mehr gesehen. Wir erhalten \u00f6fter Vorher-Nachher-Fotos von Gartenprojekten und freuen uns immer riesig, wenn wirklich sch\u00f6ne Naturg\u00e4rten mit unsern Produkten entstehen.<\/p>\n<p><strong>Aber dieser Vorher-Nachher-Vergleich war etwas sehr au\u00dfergew\u00f6hnliches!<\/strong><\/p>\n<figure id=\"attachment_17569\" aria-describedby=\"caption-attachment-17569\" style=\"width: 992px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-medium wp-image-17569\" src=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/dachterrasse-gestalten-vorher-992x744.jpg\" alt=\"Dachterrasse beschatten vorher\" width=\"992\" height=\"744\" srcset=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/dachterrasse-gestalten-vorher-992x744.jpg 992w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/dachterrasse-gestalten-vorher-1200x900.jpg 1200w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/dachterrasse-gestalten-vorher-384x288.jpg 384w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/dachterrasse-gestalten-vorher-576x432.jpg 576w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/dachterrasse-gestalten-vorher-768x576.jpg 768w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/dachterrasse-gestalten-vorher-800x600.jpg 800w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/dachterrasse-gestalten-vorher.jpg 1500w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/><figcaption id=\"caption-attachment-17569\" class=\"wp-caption-text\"><em>So sah die Dachterrasse vor der Umgestaltung aus<\/em><\/figcaption><\/figure>\n<\/div>\n<div><\/div>\n<div>\n<p>\u00dcbrigens: Vorher-Nachher-Bilder haben meist sehr gute Chancen bei unserem <strong><a href=\"https:\/\/adequat.eu\/de\/wettbewerb\/\">Foto-Wettbewerb<\/a><\/strong> zu gewinnen \ud83d\ude09<\/p>\n<h3>Dachterrasse als Wohlf\u00fchloase<\/h3>\n<p>Eine leblose Dachterrasse, die viel Liebe ben\u00f6tigt, damit man sich auch wieder gern dort aufh\u00e4lt. Das haben Nils und Sylvia geschafft und d\u00fcrfen sich nun \u00fcber ihre neue Wohlf\u00fchloase freuen.<\/p>\n<\/div>\n<figure id=\"attachment_17467\" aria-describedby=\"caption-attachment-17467\" style=\"width: 822px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\" wp-image-17467\" src=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Posten-Kastanienhols-13-16-cm-992x1240.jpeg\" alt=\"\" width=\"822\" height=\"1028\" srcset=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Posten-Kastanienhols-13-16-cm-992x1240.jpeg 992w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Posten-Kastanienhols-13-16-cm-1200x1500.jpeg 1200w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Posten-Kastanienhols-13-16-cm-384x480.jpeg 384w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Posten-Kastanienhols-13-16-cm-576x720.jpeg 576w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Posten-Kastanienhols-13-16-cm-768x960.jpeg 768w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Posten-Kastanienhols-13-16-cm.jpeg 1440w\" sizes=\"(max-width: 822px) 100vw, 822px\" \/><figcaption id=\"caption-attachment-17467\" class=\"wp-caption-text\"><em>Nachher: Dachterrasse Bedachung mit Kastanienpfosten<\/em><\/figcaption><\/figure>\n<p>Vielleicht fragen Sie sich jetzt : &#8222;Warum sollte ich gerade Pfosten aus Kastanienholz f\u00fcr die Beschattung meiner Dachterrasse w\u00e4hlen? Kann ich nicht irgendein anderes Holz nehmen?&#8220;<\/p>\n<p>Diese Frage m\u00f6chten wir gern beantworten. Bei unseren Kastanienpfosten handelt es sich nicht um irgendein Kastanienholz, sondern um das Holz der <a href=\"https:\/\/adequat.eu\/de\/aktuell\/die-edelkastanie-ein-geschenk-von-mutter-natur\/\">Edelkastanie (castanea sativa)<\/a>. Diese Holzart ist eines der besten europ\u00e4ischen H\u00f6lzer f\u00fcr den Outdoor-Bereich! Denn das Holz hat einen extrem hohen Gehalt an Gerbs\u00e4ure. Durch diese Gerbs\u00e4ure sch\u00fctzt sich das Holz vor sch\u00e4dlichen Einfl\u00fcssen, die im Au\u00dfenbereich vorkommen: vor der Witterung, vor Insektenbefall und vor Schimmel und Pilzen!\u00a0Selbst extreme K\u00e4lte und Hitze und Schnee h\u00e4lt das Holz super aus!<\/p>\n<p>Das Holz l\u00e4sst sich gut verarbeiten und ist auch preislich noch erschwinglich. Zudem ist es nachhaltig, da es schnell nachw\u00e4chst und bei uns auch aus nachhaltig bewirtschafteten W\u00e4ldern (in Frankreich) stammt. Das Holz der Edelkastanie muss wegen der genannten Gerbs\u00e4ure auch nicht behandelt werden, kein Lack, kein Holzschutzmittel, gar nichts! Das macht es besonders im Au\u00dfenbereich zu einer immer beliebteren Holzart.<\/p>\n<p>Und es sieht auch einfach wundersch\u00f6n aus \ud83d\ude42<\/p>\n<h2>Gem\u00fctliche Dachterrasse<\/h2>\n<p>Auch wenn die Konstruktion \u00fcber der Dachterrasse in erster Linie einen k\u00fchlen Platz f\u00fcr den Nachmittag bietet, hat eine so gem\u00fctlich gestaltete Dachterrasse auch am sp\u00e4ten Abend noch ihren Reiz: Durch das nat\u00fcrliche Holz und die warmen Farben entsteht eine ganz besondere Raum-Atmosph\u00e4re.<\/p>\n<figure id=\"attachment_17462\" aria-describedby=\"caption-attachment-17462\" style=\"width: 992px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-medium wp-image-17462\" src=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-992x992.jpeg\" alt=\"\" width=\"992\" height=\"992\" srcset=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-992x992.jpeg 992w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-800x800.jpeg 800w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-150x150.jpeg 150w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-1200x1200.jpeg 1200w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-384x384.jpeg 384w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-576x576.jpeg 576w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-768x768.jpeg 768w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-1920x1920.jpeg 1920w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-2560x2560.jpeg 2560w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-verschiedene-Massen-100x100.jpeg 100w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/><figcaption id=\"caption-attachment-17462\" class=\"wp-caption-text\"><em>Dachterrasse Beschattung: Gem\u00fctlich und romantisch am Abend\u00a0<\/em><\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_17461\" aria-describedby=\"caption-attachment-17461\" style=\"width: 628px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\" wp-image-17461\" src=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-Adequat-992x1240.jpeg\" alt=\"\" width=\"628\" height=\"785\" srcset=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-Adequat-992x1240.jpeg 992w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-Adequat-1200x1500.jpeg 1200w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-Adequat-384x480.jpeg 384w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-Adequat-576x720.jpeg 576w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-Adequat-768x960.jpeg 768w, https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm-Adequat.jpeg 1440w\" sizes=\"(max-width: 628px) 100vw, 628px\" \/><figcaption id=\"caption-attachment-17461\" class=\"wp-caption-text\"><em>Kastanienpfosten f\u00fcr die Beschattung der Dachterrasse\u00a0<\/em><\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Dachterrasse Beschattung: Halbschatten<\/h2>\n<p>Achja, der Halbschatten. Wenn es zu warm in der vollen Sonne ist, aber man auch nicht im Schatten sitzen m\u00f6chte. Was braucht man dann? Halbschatten. Diesen beliebten Halbschatten findet man oft unter B\u00e4umen an. Was aber, wenn kein Baum da ist? Dann ist eine Pergola DIE L\u00f6sung. Sylvia und Nils haben also diese Pergola aus. Kastanienpfosten und Bambusmatten gebaut. Sieht gem\u00fctlich aus, oder?<\/p>\n<figure id=\"attachment_17463\" aria-describedby=\"caption-attachment-17463\" style=\"width: 979px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\" wp-image-17463\" src=\"https:\/\/adequat.eu\/de\/wp-content\/uploads\/sites\/3\/2022\/07\/Kastanien-Pfosten-13-16-cm.jpeg\" alt=\"\" width=\"979\" height=\"551\" \/><figcaption id=\"caption-attachment-17463\" class=\"wp-caption-text\"><em>Pergola aus Kastanienpfosten (\u00d8 13-16 cm)\u00a0und Bambusmatten<\/em><\/figcaption><\/figure>\n<p>Neben Sylvia und Nils haben viele weitere Kunden schon eine Pergola aus unseren Rundholzpfosten gebaut. In <a href=\"https:\/\/adequat.eu\/de\/aktuell\/pergola-bauen\/\">diesem Artikel<\/a> gibt es eine sehr ausf\u00fchrliche Anleitung.<\/p>\n<p>&nbsp;<\/p>\n<h2>Fragen zur Dachterrasse Beschattung?<\/h2>\n<p>W\u00fcnschen Sie sich auch eine Beschattung Ihrer Dachterrasse? Haben Sie Fragen dazu, wie man so ein Projekt realisieren k\u00f6nnte? Kontaktieren Sie uns, wir helfen Ihnen gern!<\/p>\n<p>Email: rachel@adequat.eu<\/p>\n<p>&nbsp;<\/p>\n<h3>Dachterrasse Beschattung mit Sonnensegel<\/h3>\n<p>Wenn Sie nicht unbedingt auf Halbschatten aus sind, dann w\u00e4re alternativ auch die Beschattung der Dachterrasse mit einem Sonnensegel eine Idee. F\u00fcr die Befestigung eignen sich unsere Holzpfosten aus Robinie sehr gut. <a href=\"https:\/\/adequat.eu\/de\/aktuell\/sonnensegel-pfosten-aus-holz\/\">In diesem Artikel<\/a> erfahren Sie mehr dar\u00fcber&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sylvia und Nils haben eine Dachterrasse neu gestaltet und eine Bedachung mit Kastanienholz gebaut.<\/p>\n","protected":false},"author":7,"featured_media":17465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_trash_the_other_posts":false,"ep_exclude_from_search":false,"iawp_total_views":708,"editor_notices":[],"footnotes":""},"categories":[335,707,428,339,699,715,714],"tags":[],"class_list":["post-17570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-gartenideen","category-anwendungen","category-projekte","category-pfaehle","category-sitzecke-terrasse","category-sonnenschutz"],"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/posts\/17570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/comments?post=17570"}],"version-history":[{"count":7,"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/posts\/17570\/revisions"}],"predecessor-version":[{"id":41786,"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/posts\/17570\/revisions\/41786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/media\/17465"}],"wp:attachment":[{"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/media?parent=17570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/categories?post=17570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adequat.eu\/de\/wp-json\/wp\/v2\/tags?post=17570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}