{"id":7048,"date":"2016-02-18T23:00:00","date_gmt":"2016-02-18T22:00:00","guid":{"rendered":"https:\/\/adequat.eu\/fr\/blog\/2016\/02\/18\/portails-anglais\/"},"modified":"2025-10-31T10:01:21","modified_gmt":"2025-10-31T09:01:21","slug":"portails-anglais","status":"publish","type":"post","link":"https:\/\/adequat.eu\/fr-be\/projets\/portails\/portails-anglais\/","title":{"rendered":"Projet portails anglais"},"content":{"rendered":"<p>Vous trouverez ici des projets pour lesquels des portails anglais ont \u00e9t\u00e9 plac\u00e9s. La photo vous informe sur le portail et le bois utilis\u00e9.<\/p>\n<div id='gallery-1' class='gallery galleryid-7048 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-180-breed-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-180-breed-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7049\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-180-breed-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-180-breed-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7049'>\n\t\t\t\tPortail d\u2019acc\u00e8s anglais ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-240-breed-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-240-breed-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7050\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-240-breed-2-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-240-breed-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7050'>\n\t\t\t\tPortail d\u2019acc\u00e8s anglais ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-240-breed-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-240-breed-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7051\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-240-breed-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-eiken-2-x-240-breed-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7051'>\n\t\t\t\tPortail d\u2019acc\u00e8s anglais ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-van-240-breed-met-detail-fotos-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-van-240-breed-met-detail-fotos-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7052\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-van-240-breed-met-detail-fotos-2-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-van-240-breed-met-detail-fotos-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7052'>\n\t\t\t\tPortail d\u2019acc\u00e8s anglais douglas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-van-240-breed-met-detail-fotos-1-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-van-240-breed-met-detail-fotos-1-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7053\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-van-240-breed-met-detail-fotos-1-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-toegangspoort-van-240-breed-met-detail-fotos-1-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7053'>\n\t\t\t\tPortail d\u2019acc\u00e8s anglais douglas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-douglas-2-X-150-breed-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-douglas-2-X-150-breed-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7054\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-douglas-2-X-150-breed-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-douglas-2-X-150-breed-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7054'>\n\t\t\t\tPortail anglais pour pr\u00e9 douglas double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-douglas-2-x-150-half-openstaand-2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-douglas-2-x-150-half-openstaand-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7055\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-douglas-2-x-150-half-openstaand-2-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-douglas-2-x-150-half-openstaand-2-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7055'>\n\t\t\t\tPortail anglais pour pr\u00e9 douglas double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-2-x-240-breed-3-2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-2-x-240-breed-3-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Projet portails anglais\" aria-describedby=\"gallery-1-7056\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-2-x-240-breed-3-2-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-2-x-240-breed-3-2-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7056'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eik-2-x-330-breed-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eik-2-x-330-breed-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7057\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eik-2-x-330-breed-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eik-2-x-330-breed-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7057'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-120-breed-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-120-breed-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7058\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-120-breed-2-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-120-breed-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7058'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-150-breed-1-2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-150-breed-1-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Double portail anglais pour pr\u00e9 ch\u00eane\" aria-describedby=\"gallery-1-6746\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-150-breed-1-2-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-150-breed-1-2-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-6746'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-150-breed-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-150-breed-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7059\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-150-breed-2-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-150-breed-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7059'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-X-150-breed-3-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-X-150-breed-3-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7060\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-X-150-breed-3-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-X-150-breed-3-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7060'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-180-breed-1-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-180-breed-1-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Portail anglais pour pr\u00e9 ch\u00eane double battant\" aria-describedby=\"gallery-1-7061\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-180-breed-1-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-180-breed-1-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7061'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-180-breed-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-180-breed-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7062\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-180-breed-2-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-180-breed-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7062'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-210-enkelepoort-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-210-enkelepoort-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7063\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-210-enkelepoort-2-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-210-enkelepoort-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7063'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-240-breed-met-verzwaarde-onderbalk-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-240-breed-met-verzwaarde-onderbalk-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7064\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-240-breed-met-verzwaarde-onderbalk-2-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-240-breed-met-verzwaarde-onderbalk-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7064'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-270-breed-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-270-breed-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7065\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-270-breed-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-dubbel-eiken-2-x-270-breed-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7065'>\n\t\t\t\tPortail anglais pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-4-dubbel-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-4-dubbel-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Portail anglai pour pr\u00e9 ch\u00eane double battant\" aria-describedby=\"gallery-1-7066\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-4-dubbel-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/Engelse-veldpoort-4-dubbel-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7066'>\n\t\t\t\tPortail anglai pour pr\u00e9 ch\u00eane double battant\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Vous trouverez ici des projets pour lesquels des portails anglais ont \u00e9t\u00e9 plac\u00e9s. La photo vous informe sur le portail et le bois utilis\u00e9.<\/p>\n","protected":false},"author":7,"featured_media":13247,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_trash_the_other_posts":false,"ep_exclude_from_search":false,"iawp_total_views":13,"editor_notices":[],"footnotes":""},"categories":[275,272],"tags":[],"class_list":["post-7048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portails","category-projets"],"acf":[],"_links":{"self":[{"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/posts\/7048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/comments?post=7048"}],"version-history":[{"count":3,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/posts\/7048\/revisions"}],"predecessor-version":[{"id":16704,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/posts\/7048\/revisions\/16704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/media\/13247"}],"wp:attachment":[{"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/media?parent=7048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/categories?post=7048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/tags?post=7048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}