{"id":7085,"date":"2017-06-01T22:00:00","date_gmt":"2017-06-01T20:00:00","guid":{"rendered":"https:\/\/adequat.eu\/fr\/blog\/2017\/06\/01\/projet-portails-cadre-ganivelle\/"},"modified":"2025-10-24T10:32:25","modified_gmt":"2025-10-24T08:32:25","slug":"projet-portails-cadre-ganivelle","status":"publish","type":"post","link":"https:\/\/adequat.eu\/fr-be\/projets\/portails\/projet-portails-cadre-ganivelle\/","title":{"rendered":"Projet portails cadre ganivelle (simple et double battant) en diff\u00e9rentes dimensions"},"content":{"rendered":"<p>Vous trouverez ici des projets pour lesquels des portails cadre ganivelle ont \u00e9t\u00e9 plac\u00e9s. La photo vous indique les diff\u00e9rentes dimensions possibles du portail.<\/p>\n<div id='gallery-1' class='gallery galleryid-7085 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-cm-1-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-cm-1-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7086\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-cm-1-1-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-cm-1-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7086'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle avec treillage 100 x 100\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-met-raster-van-6-cm.x-ms-bmp'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-met-raster-van-6-cm-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Portail fran\u00e7ais cadre ganivelle Adequat\" aria-describedby=\"gallery-1-5930\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-met-raster-van-6-cm-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-met-raster-van-6-cm-384x384.jpg 384w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-met-raster-van-6-cm-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-5930'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle Adequat\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-cm-2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-cm-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7087\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-cm-2-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-100-x-100-cm-2-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7087'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle avec treillage 100 x 100\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-150-hoog-x-120-breed.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-150-hoog-x-120-breed-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7088\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-150-hoog-x-120-breed-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-150-hoog-x-120-breed-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7088'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle avec treillage 150 H x 120\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-175-hoog-x-120-breed.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-175-hoog-x-120-breed-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7089\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-175-hoog-x-120-breed-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-175-hoog-x-120-breed-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7089'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle avec treillage 175 x 120\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterscherm-100-met-2-cm-afstand-en-een-dubbele-raamwerkpoort.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterscherm-100-met-2-cm-afstand-en-een-dubbele-raamwerkpoort-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7090\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterscherm-100-met-2-cm-afstand-en-een-dubbele-raamwerkpoort-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterscherm-100-met-2-cm-afstand-en-een-dubbele-raamwerkpoort-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7090'>\n\t\t\t\tPortail cadre ganivelle ch\u00e2taignier double 100 cm hauteur\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7091\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7091'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle 100 cm de hauteur Lattes de treillis 100cm\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-raamwerkpoortje.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-raamwerkpoortje-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7092\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-raamwerkpoortje-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-raamwerkpoortje-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7092'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle 100 cm de hauteur Lattes de treillis 100cm\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-raamwerkpoort.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-raamwerkpoort-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-6140\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-raamwerkpoort-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-raamwerkpoort-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-6140'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle 100 cm de hauteur Lattes de treillis 100cm\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-een-raamwerkpoort.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-een-raamwerkpoort-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7093\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-een-raamwerkpoort-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterlatten-en-een-raamwerkpoort-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7093'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle 100 cm de hauteur Lattes de treillis 100cm\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/hekwerk-van-halfronde-palen-rasterlatten-en-een-raamwerkpoort.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/hekwerk-van-halfronde-palen-rasterlatten-en-een-raamwerkpoort-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-7094\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/hekwerk-van-halfronde-palen-rasterlatten-en-een-raamwerkpoort-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/hekwerk-van-halfronde-palen-rasterlatten-en-een-raamwerkpoort-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-7094'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle 100 cm de hauteur Lattes de treillis 100cm\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<div id='gallery-2' class='gallery galleryid-7085 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-2-x-100-x-100-met-raster-van-6-cm-latafstand.x-ms-bmp'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-2-x-100-x-100-met-raster-van-6-cm-latafstand-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"portails cadre ganivelle\" aria-describedby=\"gallery-2-5929\" srcset=\"https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-2-x-100-x-100-met-raster-van-6-cm-latafstand-150x150.jpg 150w, https:\/\/adequat.eu\/fr-be\/wp-content\/uploads\/sites\/6\/2020\/10\/rasterpoort-van-2-x-100-x-100-met-raster-van-6-cm-latafstand-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-5929'>\n\t\t\t\tPortail fran\u00e7ais cadre ganivelle double battant\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Vous trouverez ici des projets pour lesquels des portails cadre ganivelle ont \u00e9t\u00e9 plac\u00e9s. La photo vous indique les diff\u00e9rentes dimensions possibles du portail.<\/p>\n","protected":false},"author":5,"featured_media":5929,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_trash_the_other_posts":false,"ep_exclude_from_search":false,"iawp_total_views":5,"editor_notices":[],"footnotes":""},"categories":[275,272],"tags":[],"class_list":["post-7085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portails","category-projets"],"acf":[],"_links":{"self":[{"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/posts\/7085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/comments?post=7085"}],"version-history":[{"count":3,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/posts\/7085\/revisions"}],"predecessor-version":[{"id":16667,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/posts\/7085\/revisions\/16667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/media\/5929"}],"wp:attachment":[{"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/media?parent=7085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/categories?post=7085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adequat.eu\/fr-be\/wp-json\/wp\/v2\/tags?post=7085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}