{"id":5985,"date":"2015-08-27T20:13:37","date_gmt":"2015-08-27T18:13:37","guid":{"rendered":"https:\/\/adequat.eu\/fr\/product\/portail-francais-cadre-ganivelle-double-battant-100-cm-de-hauteur\/"},"modified":"2025-10-23T16:34:04","modified_gmt":"2025-10-23T14:34:04","slug":"portail-francais-cadre-ganivelle-double-battant-100-cm-de-hauteur","status":"publish","type":"product","link":"https:\/\/adequat.eu\/fr\/product\/portails\/portail-cadre-ganivelle-chataignier-double-100-cm-hauteur\/","title":{"rendered":"Portail cadre ganivelle ch\u00e2taignier double 100 cm hauteur"},"content":{"rendered":"<p>Le portail fran\u00e7ais cadre ganivelle double battant 100 cm a une largeur maximale de 500 cm. Des portails plus larges deviendraient instables. Toutes les largeurs de portail sont possibles d\u00e8s lors qu\u2019elles ne d\u00e9passent pas cette largeur maximale. Vous pouvez s\u00e9lectionner une taille standard dans le tableau ci-dessus pour en conna\u00eetre le prix. Si vous choisissez un taille interm\u00e9diaire, c\u2019est le prix de la taille au-dessus qui sera appliqu\u00e9.<br \/>\nPar exemple: un portail de 140 cm de largeur aura le prix d\u2019un portail de 150 cm de largeur. Nous pouvons vous donner les prix d\u2019autres hauteurs sur <a href=\"https:\/\/adequat.eu\/fr\/devis\/\">demande<\/a>.<\/p>\n<h2>Le portail fran\u00e7ais cadre ganivelle double battant 100 cm<\/h2>\n<ul>\n<li>Le portail fran\u00e7ais cadre ganivelle double battant 100 cm est g\u00e9n\u00e9ralement associ\u00e9 \u00e0 la <a href=\"https:\/\/adequat.eu\/fr\/product\/clotures\/ganivelle-francais\/ganivelle-francaise-100-cm-hauteur\/\">cl\u00f4ture ganivelle de m\u00eame hauteur<\/a>.<\/li>\n<li>Le portail est livr\u00e9 avec deux poteaux \u00e0 planter (<a href=\"https:\/\/adequat.eu\/fr\/product\/piquets\/piquets-en-chataignier\/piquet-en-chataignier-o-1012-cm\/\">diam\u00e8tre 10\/12, longueur 175 cm<\/a>) , les charni\u00e8res et la serrure.<\/li>\n<li>Les poteaux du portail fran\u00e7ais cadre ganivelle double battant de 100 cm de hauteur sont compos\u00e9s de piquets de 7 \u00e0 9 cm de diam\u00e8tre, et les poutres sont compos\u00e9es de piquets de 4 \u00e0 6 cm de diam\u00e8tre.<\/li>\n<li>Pour un portail fran\u00e7ais double battant, vous payez le prix de deux portails simples moins 30\u20ac. Toutes les combinaisons sont possibles.<\/li>\n<li>Si vous commandez une porte double, le pied de scellement sera install\u00e9 sur la section de gauche, conform\u00e9ment \u00e0 nos standards de fabrication. Le verrou sera \u00e0 droite. Si vous commandez une porte double compos\u00e9e de deux sections de tailles diff\u00e9rentes, le pied de scellement sera install\u00e9 sur la plus grande. Vous souhaitez une autre configuration ? Donnez-nous vos indications dans la partie commentaire lors de votre commande.ATTENTION : pour \u00e9viter tout dommages lors du transport, nous positionnons <a href=\"https:\/\/adequat.eu\/fr\/general\/le-mystere-du-bidule-manquant\/\">la g\u00e2che de la serrure sur le poteau \u00e0 planter<\/a>. Vous pouvez facilement la d\u00e9tacher pour la monter au bon endroit.<\/li>\n<\/ul>\n<h2>Portail fran\u00e7ais cadre ganivelle<\/h2>\n<ul>\n<li>Ce portail est aussi disponible en\u00a0<a href=\"https:\/\/adequat.eu\/fr\/product\/portails\/portail-cadre-ganivelle-chataignier-simple-100-cm-hauteur\/\">portail fran\u00e7ais cadre ganivelle 100 cm de hauteur<\/a>.<\/li>\n<\/ul>\n<p><div class=\"embed-responsive embed-responsive-16by9\"><iframe loading=\"lazy\" title=\"Mise en place d&#039;une cl\u00f4ture ganivelle et d&#039;un portail\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/J3x54M2DOqc?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/adequat.eu\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le portail fran\u00e7ais cadre ganivelle double battant 100 cm a une largeur maximale de 500 cm. Des portails plus larges deviendraient instables. Toutes les largeurs&#8230;<\/p>\n","protected":false},"featured_media":5986,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_trash_the_other_posts":false,"ep_exclude_from_search":false,"iawp_total_views":280,"editor_notices":[]},"product_brand":[],"product_cat":[523,209,422,86,412,429,431,434,436,437,440,428],"product_tag":[339],"class_list":["post-5985","product","type-product","status-publish","has-post-thumbnail","product_cat-cadre","product_cat-chataignier","product_cat-double","product_cat-portails","product_cat-ganivelle","product_cat-100-cm","product_cat-120-cm","product_cat-150-cm","product_cat-180-cm","product_cat-200-cm","product_cat-250-cm","product_cat-80-cm","product_tag-google-shopping","first","instock","shipping-taxable","purchasable","product-type-composite"],"composite_virtual":false,"composite_layout":"single","composite_add_to_cart_form_location":"default","composite_editable_in_cart":false,"composite_sold_individually_context":"product","composite_shop_price_calc":"min_max","composite_components":[{"id":"1608219890","title":"Portail gauche","description":"","query_type":"product_ids","query_ids":[5928],"default_option_id":5928,"thumbnail_id":"","thumbnail_src":"","quantity_min":1,"quantity_max":1,"priced_individually":true,"shipped_individually":false,"optional":false,"discount":"","options_style":"dropdowns","pagination_style":"classic","display_prices":"absolute","show_sorting_options":false,"show_filtering_options":false,"attribute_filter_ids":[],"select_action":"view","product_title_visible":false,"product_descr_visible":false,"product_price_visible":true,"product_thumb_visible":false,"subtotal_visible_product":true,"subtotal_visible_cart":true,"subtotal_visible_orders":true},{"id":"1608219891","title":"Portail droit","description":"","query_type":"product_ids","query_ids":[5928],"default_option_id":5928,"thumbnail_id":"","thumbnail_src":"","quantity_min":1,"quantity_max":1,"priced_individually":true,"shipped_individually":false,"optional":false,"discount":"","options_style":"dropdowns","pagination_style":"classic","display_prices":"absolute","show_sorting_options":false,"show_filtering_options":false,"attribute_filter_ids":[],"select_action":"view","product_title_visible":false,"product_descr_visible":false,"product_price_visible":true,"product_thumb_visible":false,"subtotal_visible_product":true,"subtotal_visible_cart":true,"subtotal_visible_orders":true}],"composite_scenarios":[],"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/adequat.eu\/fr\/wp-json\/wp\/v2\/product\/5985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adequat.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adequat.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/adequat.eu\/fr\/wp-json\/wp\/v2\/comments?post=5985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adequat.eu\/fr\/wp-json\/wp\/v2\/media\/5986"}],"wp:attachment":[{"href":"https:\/\/adequat.eu\/fr\/wp-json\/wp\/v2\/media?parent=5985"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adequat.eu\/fr\/wp-json\/wp\/v2\/product_brand?post=5985"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adequat.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=5985"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adequat.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=5985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}