{"id":41604,"date":"2023-04-06T15:53:55","date_gmt":"2023-04-06T13:53:55","guid":{"rendered":"https:\/\/adequat.eu\/nl\/?post_type=product&#038;p=41604"},"modified":"2024-03-25T17:55:17","modified_gmt":"2024-03-25T16:55:17","slug":"picknicktafel-kastanje-rustiek","status":"publish","type":"product","link":"https:\/\/adequat.eu\/nl\/product\/tuininrichting\/meubelen\/kastanjehout-meubelen\/picknicktafel-kastanje-rustiek\/","title":{"rendered":"Picknicktafel kastanje rustiek"},"content":{"rendered":"<p>Deze picknicktafel kastanje rustiek is weer zo&#8217;n knap staaltje vakmanschap uit onze werkplaats. Wat een prachtige rustieke en robuuste picknicktafel. Ziet u zichzelf al zitten? Deze picknicktafel past perfect in een landelijke omgeving &#8211; boerderij, boomgaard of park &#8211; maar ook bij een nieuw en modern huis vindt ie zo z&#8217;n plekje.<\/p>\n<p>Deze rustieke picknicktafel is gemaakt van dikke kastanje balken, rondhout en planken en is bijzonder duurzaam.<\/p>\n<h2>Picknicktafel kastanje rustiek<\/h2>\n<p>Onze picknicktafel kastanje rustiek is ongeveer 180 &#8211; 200 cm breed en we kunnen de picknicktafel in twee verschillende lengtes &#8211; 200 cm en 300 cm &#8211; maken. Wilt u het net even anders, ook dat is geen probleem. We maken graag een <a href=\"https:\/\/adequat.eu\/nl\/offerte\/offerteformulier\/\">offerte<\/a> voor u!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deze picknicktafel kastanje rustiek is weer zo&#8217;n knap staaltje vakmanschap uit onze werkplaats. Wat een prachtige rustieke en robuuste picknicktafel. Ziet u zichzelf al zitten?&#8230;<\/p>\n","protected":false},"featured_media":41612,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_trash_the_other_posts":false,"ep_exclude_from_search":false,"iawp_total_views":199,"editor_notices":[]},"product_brand":[],"product_cat":[641,576,575],"product_tag":[],"class_list":["post-41604","product","type-product","status-publish","has-post-thumbnail","product_cat-kastanjehout-meubelen","product_cat-meubelen","product_cat-overig","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"composite_virtual":false,"composite_layout":"","composite_add_to_cart_form_location":"","composite_editable_in_cart":false,"composite_sold_individually_context":"","composite_shop_price_calc":"","composite_components":[],"composite_scenarios":[],"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/product\/41604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/media\/41612"}],"wp:attachment":[{"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/media?parent=41604"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/product_brand?post=41604"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/product_cat?post=41604"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/product_tag?post=41604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}