{"id":872,"count":6,"description":"","link":"https:\/\/adequat.eu\/nl\/producten\/palen\/houten-palen-600-cm\/","name":"Houten palen 600 cm","slug":"houten-palen-600-cm","taxonomy":"product_cat","parent":636,"meta":[],"menu_order":89,"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/product_cat\/872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/product_cat\/636"}],"wp:post_type":[{"href":"https:\/\/adequat.eu\/nl\/wp-json\/wp\/v2\/product?product_cat=872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}